{"id":1131,"date":"2021-10-23T15:13:47","date_gmt":"2021-10-23T15:13:47","guid":{"rendered":"http:\/\/www.112canarias.com\/112\/2021\/10\/23\/sanchez-se-reune-de-nuevo-con-los-comites-director-y-cientifico-del-pevolca-y-reitera-su-compromiso-con-la-palma\/"},"modified":"2021-10-23T15:13:47","modified_gmt":"2021-10-23T15:13:47","slug":"sanchez-se-reune-de-nuevo-con-los-comites-director-y-cientifico-del-pevolca-y-reitera-su-compromiso-con-la-palma","status":"publish","type":"post","link":"https:\/\/www.112canarias.com\/112\/sanchez-se-reune-de-nuevo-con-los-comites-director-y-cientifico-del-pevolca-y-reitera-su-compromiso-con-la-palma\/","title":{"rendered":"S\u00e1nchez se re\u00fane de nuevo con los Comit\u00e9s Director y Cient\u00edfico del PEVOLCA y reitera su compromiso con La Palma"},"content":{"rendered":"<p style=\"text-align: justify;\"><\/p>\n<p style=\"text-align: justify;\"><strong>Las coladas hasta el mediod\u00eda de este s\u00e1bado se han ralentizado y se est\u00e1 produciendo una redistribuci\u00f3n del aporte l\u00e1vico del volc\u00e1n en varias de ellas<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>La superficie afectada se estima en 848 hect\u00e1reas, 3,4 m\u00e1s respecto al anterior dato disponible<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Hay un total de 429 personas albergadas en hoteles,\u00a0<\/strong><strong>56 de las cuales se encuentran en Los Llanos de Aridane y 373 en Fuencaliente, y adem\u00e1s hay otras<\/strong><strong>\u00a046 en centros sociosanitarios<\/strong><\/p>\n<p style=\"text-align: justify;\">El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, y el de Canarias, \u00c1ngel V\u00edctor Torres, participaron hoy en la reuni\u00f3n del Comit\u00e9 Director del Plan Especial de Protecci\u00f3n Civil y Atenci\u00f3n de Emergencias por Riesgo Volc\u00e1nico de Canarias (PEVOLCA) del Gobierno de Canarias, que dirige el consejero de Administraciones P\u00fablicas, Justicia y Seguridad, Julio P\u00e9rez. En dicho encuentro se analiz\u00f3 la evoluci\u00f3n del proceso eruptivo en base al informe del Comit\u00e9 Cient\u00edfico detect\u00e1ndose una ralentizaci\u00f3n de las coladas y una redistribuci\u00f3n del aporte l\u00e1vico en las mismas. Se sigue monitorizando el avance de las coladas, con especial atenci\u00f3n a la m\u00e1s pr\u00f3xima a La Laguna para determinar su posible rumbo.<\/p>\n<p style=\"text-align: justify;\">El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, que visit\u00f3 La Palma por quinta vez, agradeci\u00f3 a la ciudadan\u00eda palmera, a los cient\u00edficos y a todos los servicios intervinientes en la gesti\u00f3n de esta emergencia el trabajo realizado ante una \u201csituaci\u00f3n que sigue siendo cr\u00edtica\u201d. Por ello, reiter\u00f3 el compromiso del Gobierno de Espa\u00f1a con toda la sociedad palmera y sus instituciones para lograr reconstruir esta isla.<\/p>\n<p style=\"text-align: justify;\">Respecto a la evoluci\u00f3n del proceso eruptivo El Director T\u00e9cnico del PEVOLCA, Miguel \u00c1ngel Morcuende, afirm\u00f3 que se ha producido una ralentizaci\u00f3n de las coladas\u00a0 y una redistribuci\u00f3n del aporte l\u00e1vico por varias de ellas, incluyendo la primigenia, debido a peque\u00f1as roturas parciales del conelete situado en la ladera noroeste del cono principal y a la existencia de tubos volc\u00e1nicos. Esa ralentizaci\u00f3n ha permitido realizar los acompa\u00f1amientos a los propietarios para la retirada de enseres de sus viviendas con relativa normalidad.<\/p>\n<p style=\"text-align: justify;\">La colada que afecta a La Laguna sigue frenada en el centro del barrio pero se contin\u00faa monitorizando para determinar su posible rumbo hacia la vertiente sur o norte de la Monta\u00f1a de La Laguna.\u00a0<\/p>\n<p style=\"text-align: justify;\">El n\u00famero de personas albergadas en centros hoteleros asciende, en estos momentos, a 429. De ellas, 56 se encuentran en un centro hotelero de Los Llanos de Aridane y 373 se hospedan en el hotel de Fuencaliente. Todas est\u00e1n siendo atendidas por Cruz Roja, en coordinaci\u00f3n con los servicios sociales municipales. Adem\u00e1s, hay 46 personas dependientes en centros sociosanitarios insulares.<\/p>\n<p style=\"text-align: justify;\">En rueda de prensa, la responsable nacional de Vigilancia Volc\u00e1nica del Instituto Geogr\u00e1fico Nacional (IGN), Carmen L\u00f3pez, inform\u00f3 que la sismicidad contin\u00faa registr\u00e1ndose en las mismas zonas aunque se aprecia un aumento de la intensidad en la intermedia. No se descarta que puedan producirse sismos de mayor magnitud sentidos por la poblaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La deformaci\u00f3n se mantiene estable en la estaciones cercanas al cono volc\u00e1nico pero con una tendencia a la baja en la zonas m\u00e1s alejadas del foco eruptivo.<\/p>\n<p style=\"text-align: justify;\">La calidad del aire contin\u00faa mejorando debido al aumento de la capa de inversi\u00f3n t\u00e9rmica y a la reducci\u00f3n de las part\u00edculas en suspensi\u00f3n. No obstante, el Director T\u00e9cnico del PEVOLCA record\u00f3 que las personas con problemas de salud y respiratorios deben utilizar las mascarillas FFP2, aunque tambi\u00e9n es recomendable su uso en general.<\/p>\n<p style=\"text-align: justify;\">Ante la previsi\u00f3n de lluvias d\u00e9biles en el Valle de Aridane, se insisti\u00f3 en la importancia de limpiar las cubiertas ya que las precipitaciones aumentan el peso de las cenizas, a la vez que se alert\u00f3 del riesgo de posibles escorrent\u00edas por la impermeabilidad de las coladas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Infraestructuras afectadas<\/strong><\/p>\n<p style=\"text-align: justify;\">Con respecto a la superficie afectada por el proceso eruptivo, se estima en 848,96 hect\u00e1reas, 3,4 hect\u00e1reas m\u00e1s que el dato hecho p\u00fablico ayer, y la anchura m\u00e1xima entre los puntos extremos de las coladas se mantiene en 2.900 metros, aproximadamente, aunque dentro de esta extensi\u00f3n existen zonas que no han sido afectadas por la lava.<\/p>\n<p style=\"text-align: justify;\">En cuanto al n\u00famero de construcciones destruidas o da\u00f1adas facilitados por el Catastro no se registran variaciones por lo que las mismas ascienden a 1.280 edificaciones. De ellas, 1.030 son de uso residencial, 132 agr\u00edcola, 64 industrial, 30 de ocio y hosteler\u00eda, 11 de uso p\u00fablico y 14 de otros usos.<\/p>\n<p style=\"text-align: justify;\">El Comit\u00e9 Director analiz\u00f3 tambi\u00e9n el estado de los servicios b\u00e1sicos (electricidad, telefon\u00eda, escuelas y colegios) en los que no se han registrado incidentes relevantes, as\u00ed como las obras de las desaladoras port\u00e1tiles en Puerto Naos que han comenzado a realizar las primeras pruebas de conexi\u00f3n en el d\u00eda de hoy.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, se ha trasladado el Puesto de Mando Avanzado de la emergencia desde el Centro de Visitantes de El Paso a la nave de la antigua f\u00e1brica de tabaco (JTI) del mismo municipio, ubicada en la LP-3, con la Avenida Venezuela. Este traslado se realiza para mejorar la operativas de los servicios intervinientes y la comodidad de las personas usuarias.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Dictamen diario del Comit\u00e9 Cient\u00edfico<\/strong><\/p>\n<p style=\"text-align: justify;\">Previamente a la reuni\u00f3n del Comit\u00e9 Director del PEVOLCA se reuni\u00f3 el Comit\u00e9 Cient\u00edfico del Plan, en el que sus integrantes expusieron sus conclusiones sobre la evoluci\u00f3n del fen\u00f3meno eruptivo desde el d\u00eda de ayer. Este Comit\u00e9 Cient\u00edfico est\u00e1 coordinado por la Direcci\u00f3n General de Seguridad y Emergencias del Gobierno de Canarias y lo integran representantes del Instituto Geogr\u00e1fico Nacional (IGN), Consejo Superior de Investigaciones Cient\u00edficas (CSIC), Instituto Volcanol\u00f3gico de Canarias (Involcan), Instituto Geol\u00f3gico y Minero de Espa\u00f1a (IGME), Agencia Estatal de Meteorolog\u00eda (AEMET), Instituto Espa\u00f1ol de Oceanograf\u00eda (IEO), Universidad de La Laguna y Universidad de Las Palmas de Gran Canaria.<\/p>\n<p style=\"text-align: justify;\">Tales conclusiones fueron:<\/p>\n<p style=\"text-align: justify;\">\u201cLa erupci\u00f3n fisural contin\u00faa mostrando mecanismo estromboliano (esto es, un mecanismo de car\u00e1cter mixto, con fases de explosividad que producen dep\u00f3sitos pirocl\u00e1sticos y fases efusivas que producen las coladas de lava, de forma simult\u00e1nea), ahora con predominio de la fase efusiva. En volcanolog\u00eda la magnitud de las erupciones volc\u00e1nicas se mide en la escala del \u00cdndice de Explosividad Volc\u00e1nica (VEI por sus siglas en ingl\u00e9s) con valores entre 0 y 8; en el caso de esta erupci\u00f3n el VEI estimado hasta ahora es 2.<\/p>\n<p style=\"text-align: justify;\">El flujo principal de las coladas de lava discurre por el flanco norte, bajando por la parte norte de las coladas previas, siguiendo trayectorias hacia el oeste y noroeste, dentro de la zona de exclusi\u00f3n actual. A la salida del centro de emisi\u00f3n, el flujo se concentra en un canal l\u00e1vico escalonado, que posteriormente se ramifica en canales y tubos volc\u00e1nicos. Siguen activos los centros de emisi\u00f3n del cono, con expulsi\u00f3n de piroclastos de manera continua y con pulsos freatomagm\u00e1ticos intermitentes y uno con emisi\u00f3n de lava.<\/p>\n<p style=\"text-align: justify;\">No se descarta la aparici\u00f3n de nuevos centros de emisi\u00f3n en el entorno del cono principal, as\u00ed como otros observables superficiales (emisiones visibles de gas) dentro de la zona de exclusi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La morfolog\u00eda del cono cambia de manera reiterada por los sucesivos procesos de crecimiento y reconfiguraci\u00f3n. Desde la noche de ayer se est\u00e1n produciendo peque\u00f1as roturas parciales del conelete (cono de piroclastos soldados), situado en la ladera NO del cono principal. El proceso eruptivo puede mostrar episodios de incremento y disminuci\u00f3n de la actividad estromboliana, as\u00ed como pulsos con actividad freatomagm\u00e1tica.<\/p>\n<p style=\"text-align: justify;\">La altura de columna de cenizas y gases medida hoy, alcanza los 3000 m.<\/p>\n<p style=\"text-align: justify;\">Predominio de viento del nordeste a componente este con la altura. Se prev\u00e9 que el viento gire a componente sur en el estrato entre los 3000 a 5000 m. La disposici\u00f3n actual de la nube de cenizas y SO2 es hacia el suroeste del foco eruptivo y se espera que se disponga hacia el oeste\/noroeste las pr\u00f3ximas horas. La posici\u00f3n esperada del penacho supone un escenario favorable para la operatividad aeron\u00e1utica. Se han registrado precipitaciones en general de car\u00e1cter d\u00e9bil en vertiente norte y este de La Palma y estas precipitaciones (d\u00e9biles a localmente moderadas) seguir\u00e1n siendo probables para lo que queda de s\u00e1bado, domingo y lunes. Principalmente las precipitaciones se registrar\u00e1n en vertiente norte y este, as\u00ed como en zonas de interior y oeste. El efecto de la inversi\u00f3n t\u00e9rmica (de 3-4 \u00b0C) que se sit\u00faa entre 1500 a 2000 m y el r\u00e9gimen local de vientos en la zona de El Paso, Los Llanos y Tazacorte est\u00e1n produciendo una zona de convergencia que est\u00e1 favoreciendo la acumulaci\u00f3n de SO2 en esa cuenca.<\/p>\n<p style=\"text-align: justify;\">La sismicidad contin\u00faa localiz\u00e1ndose, principalmente, cercana a la sismicidad de los primeros d\u00edas, a profundidades entre 10 y 15 km. Esta sismicidad ha aumentado en su frecuencia y magnitud. Se registran tambi\u00e9n terremotos situados a profundidades superiores a 20 km, que en las \u00faltimas horas siguen teniendo una elevada magnitud, aunque con menor frecuencia. Se mantienen los valores altos de la amplitud de la se\u00f1al de tremor, con pulsos de intensificaci\u00f3n. La magnitud m\u00e1xima observada ha sido 4.3 mbLg de un evento a 36 km de profundidad, con intensidad IV EMS. La sismicidad registrada a profundidades intermedias y profundas, se enmarca en el mismo proceso eruptivo actual. No se registra sismicidad superficial significativa. El nivel de sismicidad actual sigue indicando que es posible que se produzcan m\u00e1s sismos sentidos, pudiendo alcanzarse intensidades VI (EMS) y originar peque\u00f1os derrumbes en zonas de pendiente. Se incluye informaci\u00f3n relevante sobre este tema, en el apartado de Recomendaciones del informe.<\/p>\n<p style=\"text-align: justify;\">La deformaci\u00f3n muestra un patr\u00f3n de estabilidad en el entorno del centro eruptivo y una ligera deflaci\u00f3n regional de origen profundo detectada en las estaciones m\u00e1s alejadas del centro eruptivo.<\/p>\n<p style=\"text-align: justify;\">Durante el d\u00eda de ayer (22\/10), la emisi\u00f3n de di\u00f3xido de azufre (SO2) asociado al penacho volc\u00e1nico (emanaciones visibles de gases volc\u00e1nicos) contin\u00faa registrando valores altos y acordes al proceso eruptivo, alcanzando valores de 31600 toneladas diarias (valor subestimado). As\u00ed mismo, la emisi\u00f3n difusa de di\u00f3xido de carbono (CO2), asociada a los 220 km2 de la dorsal volc\u00e1nica de Cumbre Vieja (emanaciones no visibles de gases volc\u00e1nicos), contin\u00faa reflejando una tendencia descendente durante los \u00faltimos 10 d\u00edas y ha sido estimada en 623 toneladas diarias a fecha de 22\/10. La monitorizaci\u00f3n del flujo difuso de di\u00f3xido de carbono (CO2), en la estaci\u00f3n geoqu\u00edmica de Los Llanos (LP10) refleja una mayor fracci\u00f3n magm\u00e1tica-hidrotermal que la observada en la estaci\u00f3n geoqu\u00edmica de Fuencaliente (LP08). Todas estas observaciones geoqu\u00edmicas son coherentes con el actual proceso eruptivo.<\/p>\n<p style=\"text-align: justify;\">Respecto a la calidad del aire, en lo relativo al di\u00f3xido de azufre (SO2), desde la noche de ayer se est\u00e1n registrando valores altos de concentraci\u00f3n en las estaciones de Los Llanos, El Paso, Tazacorte y Puntagorda. Los valores medios horarios se han incrementado significativamente durante las \u00faltimas horas de la madrugada y primeras de la ma\u00f1ana, de modo que, en el caso de Los Llanos, a las 9:00 horas se ha registrado el tercer valor horario consecutivo de concentraci\u00f3n por encima de los 500 \u03bcg\/m\u00b3, que es el valor de referencia de umbral de alerta a la poblaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Durante este periodo los valores registrados en las estaciones de Tazacorte y El Paso, tambi\u00e9n han registrado medias horarias superiores al valor de 500 \u03bcg\/m\u00b3. Si bien no lo han hecho durante tres horas consecutivas s\u00ed se considera que existe un riesgo de alcanzar estos niveles, por lo que se dar\u00edan las circunstancias para alertar a la poblaci\u00f3n del Valle de Aridane.<\/p>\n<p style=\"text-align: justify;\">Con respecto a las part\u00edculas menores de 10 micras (PM10), ayer se observaron de forma general unas concentraciones inferiores a d\u00edas anteriores, sin que se registre superaci\u00f3n del umbral diario (establecido en 50 \u03bcg\/m\u00b3), en ninguna de las estaciones de la red de calidad del aire.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>OBLIGACIONES Y RECOMENDACIONES<\/strong><\/p>\n<p style=\"text-align: justify;\">PENACHO MARINO:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Se sugiere prestar mucha atenci\u00f3n al pron\u00f3stico del viento para la monitorizaci\u00f3n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">de los posibles cambios de direcci\u00f3n del penacho y actuar en consecuencia, especialmente aquellas personas con el sistema respiratorio debilitado (por ejemplo, asm\u00e1ticos) ya que son m\u00e1s vulnerables a concentraciones m\u00e1s bajas.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Tambi\u00e9n se recomienda el lavado de los ojos despu\u00e9s de cualquier exposici\u00f3n, ya<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">que los s\u00edntomas, a menudo, no se perciben hasta m\u00e1s tarde.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Estos penachos marinos se pueden percibir hasta varios kil\u00f3metros de distancia de la fuente, aunque m\u00e1s diluidos. En el caso de que el penacho marino llegue a n\u00facleos poblacionales, se recomienda permanecer en el interior de las viviendas siempre que sea posible y cerrar todas las puertas y ventanas.<\/li>\n<li>Para la seguridad de la navegaci\u00f3n de embarcaciones cient\u00edficas que realizan labores cient\u00edficas en esta \u00e1rea, se recomienda mantener una distancia de al menos 500 m para las zonas activas de los deltas de lava (con aporte de lava y manifestaciones visibles), reduciendo dicha distancia a 200 m para las zonas m\u00e1s estables. La navegaci\u00f3n con fines cient\u00edficos para la gesti\u00f3n de la emergencia, se puede realizar a distancias menores, bajo la responsabilidad del armador y el capit\u00e1n o patr\u00f3n de la embarcaci\u00f3n, siempre y cuando se cuente con el visto bueno de la Direcci\u00f3n T\u00e9cnica de PEVOLCA y Capitan\u00eda Mar\u00edtima.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">COLADAS L\u00c1VICAS:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Tambi\u00e9n se recomienda no aproximarse a las coladas de lava por el riesgo de exponerse a los gases emitidos, posibles desprendimientos y las altas temperaturas.<\/li>\n<li>Ante los grandes espesores de colada de lava observados en algunos puntos, se pueden producir colapsos de su frente que, en zonas de mayor pendiente, pueden conllevar la formaci\u00f3n de grandes fragmentos de colada, que pueden desprenderse del frente de la colada y que de forma repentina alcanzando distancias de varios metros desde el frente de colada, dependiendo de la topograf\u00eda. Tambi\u00e9n en zonas de gran pendiente, se puede producir peque\u00f1os flujos pirocl\u00e1sticos.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">CAIDA DE PIROCLASTOS:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Se recuerda que est\u00e1 establecido un radio de exclusi\u00f3n de 2.5 km en torno a los centros de emisi\u00f3n para minimizar el riesgo de impacto de piroclastos y la exposici\u00f3n a los gases.<\/li>\n<li>En caso de intensificaci\u00f3n de la actividad explosiva es posible que algunas detonaciones violentas puedan producir rotura del vidrio de las ventanas. Se recomienda alejarse de las ventanas hasta un radio de 5 km desde el cono.<\/li>\n<li>En las zonas afectadas por una intensa ca\u00edda de cenizas (que se observe una clara deposici\u00f3n sobre el suelo) y m\u00e1s a\u00fan si se observa bruma, se recomienda mantenerse en espacios interiores. Al aire libre, se recomienda as\u00ed mismo el uso de mascarillas FFP2 y de sistemas de protecci\u00f3n de ojos.<\/li>\n<li>Ante la llegada de cenizas a otras islas, se recomienda en las afectadas, el uso de mascarillas quir\u00fargicas. Se recomienda la limpieza de azoteas en las que se acumulen espesores de cenizas de varios cent\u00edmetros. Se insiste en que se sigan de manera precisa el procedimiento de retirada de cenizas de azoteas y suelo indicado por Protecci\u00f3n Civil (humedecer ceniza, protecci\u00f3n de ojos, llevar mascarilla, proteger la piel, v\u00e9ase documentaci\u00f3n anexa). Para la retirada, se deben usar mascarillas FFP2, guantes, humedecer ligeramente para su barrido y evitando el uso de sopladores, salvo para la limpieza de las instalaciones aeroportuaria por personal especializado con sus EPIs correspondientes. El uso de los sopladores aumenta la re-suspensi\u00f3n de las part\u00edculas m\u00e1s perjudiciales para la salud.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Para la seguridad de cient\u00edficos en tierra dentro de la zona de exclusi\u00f3n se recomienda mantener una distancia de al menos 1000 m respecto al centro principal de emisi\u00f3n. La aproximaci\u00f3n a distancias menores puede realizarse, con fines de observaci\u00f3n cient\u00edfica para la gesti\u00f3n de la emergencia, con el visto bueno de la Direcci\u00f3n T\u00e9cnica de PEVOLCA.<\/p>\n<p style=\"text-align: justify;\">Desde el centro emisor actual en el sector sur, a distancias menores de 3 km y dentro de la zona de exclusi\u00f3n, se ha de extremar la atenci\u00f3n a cualquier fen\u00f3meno observable, minimizando la exposici\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">MOVIMIENTOS S\u00cdSMICOS:<\/p>\n<p style=\"text-align: justify;\">&#8211; El comit\u00e9 cient\u00edfico del PEVOLCA realiza un seguimiento continuo de la actividad volc\u00e1nica.<\/p>\n<p style=\"text-align: justify;\">&#8211; Tanto en casa, como en el centro de trabajo, toma medidas preventivas: refuerza las estanter\u00edas, fija l\u00e1mparas y retira objetos grandes del mobiliario.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En el exterior:<\/p>\n<p style=\"text-align: justify;\">Si te encuentras en el exterior y se registra un sismo, busca un lugar abierto y al\u00e9jate de estructuras que puedan caer a la v\u00eda y de las zonas con riesgo de derrumbe.<\/p>\n<p style=\"text-align: justify;\">Por tu seguridad, recuerda estos consejos de autoprotecci\u00f3n:\u00a0<\/p>\n<p style=\"text-align: justify;\">&#8211; Dir\u00edgete a espacios abiertos.<\/p>\n<p style=\"text-align: justify;\">&#8211; Al\u00e9jate de edificios, balcones, sem\u00e1foros, farolas, tendidos el\u00e9ctricos o \u00e1rboles.<\/p>\n<p style=\"text-align: justify;\">&#8211; No te acerques a zonas con peligro de desprendimientos.<\/p>\n<p style=\"text-align: justify;\">&#8211; Sigue las recomendaciones de las autoridades e inf\u00f3rmate por canales oficiales y medios de comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">&#8211; Si te encuentras en un veh\u00edculo, disminuye la velocidad y para el motor cuando sea posible, lejos de edificaciones y zonas escarpadas. Pon los indicadores de emergencia y permanece en el veh\u00edculo hasta que finalice el terremoto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En el interior:<\/p>\n<p style=\"text-align: justify;\">Si te sorprende un temblor en el interior de tu vivienda, mant\u00e9n la calma y sigue estos consejos de autoprotecci\u00f3n:<\/p>\n<p style=\"text-align: justify;\">&#8211; Mientras dure el temblor, no salgas al exterior.<\/p>\n<p style=\"text-align: justify;\">&#8211; Prot\u00e9gete bajo el marco de una puerta o de alg\u00fan mueble s\u00f3lido, como una mesa.<\/p>\n<p style=\"text-align: justify;\">&#8211; No te sit\u00faes cerca de ventanas.<\/p>\n<p style=\"text-align: justify;\">&#8211; Si tienes que abandonar tu casa, desconecta agua, luz y gas.<\/p>\n<p style=\"text-align: justify;\">&#8211; En caso de evacuaci\u00f3n, baja por las escaleras y no utilices el ascensor.<\/p>\n<p style=\"text-align: justify;\">&#8211; Sigue las recomendaciones de las autoridades e inf\u00f3rmate por canales oficiales y medios de comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Se recomienda a la poblaci\u00f3n en la isla de La Palma el uso de mascarillas FFP2 al aire libre.<\/p>\n<p style=\"text-align: justify;\">Sigue siendo imperativo el respeto de las zonas de exclusi\u00f3n terrestre y mar\u00edtima, para mantener la integridad f\u00edsica de las personas.<\/p>\n<p style=\"text-align: justify;\">Se ha reforzado el seguimiento continuo de la actividad y se comunicar\u00e1 cualquier cambio significativo que se observe. Mant\u00e9nganse atentos a la informaci\u00f3n que proporcionen las correspondientes autoridades de Protecci\u00f3n Civil\u201d.<\/p>\n<p>\u00a0<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_1131\" class=\"pvc_stats all  \" data-element-id=\"1131\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <\/p>\n<div class=\"pvc_clear\"><\/div>\n<div class=\"print\"><span class=\"page_title\">P\u00e1gina: <span>S\u00e1nchez se re\u00fane de nuevo con los Comit\u00e9s Director y Cient\u00edfico del PEVOLCA y reitera su compromiso con La Palma<\/span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"stmp_trans_date\">\u00daltima actualizaci\u00f3n: <span>23\/10\/2021 - 15:13:47<\/span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"stmp_trans_date\">Fecha publicaci\u00f3n: <span>23\/10\/2021 - 15:13:47<\/span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"stmp_trans_date\">Fecha creaci\u00f3n: <span>23\/10\/2021 - 15:13:47<\/span><\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Las coladas hasta el mediod\u00eda de este s\u00e1bado se han ralentizado y se est\u00e1 produciendo una redistribuci\u00f3n del aporte l\u00e1vico del volc\u00e1n en varias de ellas La superficie afectada se estima en 848 hect\u00e1reas, 3,4 m\u00e1s respecto al anterior dato disponible Hay un total de&#8230;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_1131\" class=\"pvc_stats all  \" data-element-id=\"1131\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.112canarias.com\/112\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":1541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticas"],"_links":{"self":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/comments?post=1131"}],"version-history":[{"count":0,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts\/1131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/media\/1541"}],"wp:attachment":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/media?parent=1131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/categories?post=1131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/tags?post=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}