{"id":6203,"date":"2024-03-25T15:20:13","date_gmt":"2024-03-25T15:20:13","guid":{"rendered":"https:\/\/www.112canarias.com\/112\/?p=6203"},"modified":"2024-03-25T15:20:13","modified_gmt":"2024-03-25T15:20:13","slug":"el-gobierno-de-canarias-declara-la-situacion-de-prealerta-por-fenomenos-costeros-en-todo-el-archipielago","status":"publish","type":"post","link":"https:\/\/www.112canarias.com\/112\/el-gobierno-de-canarias-declara-la-situacion-de-prealerta-por-fenomenos-costeros-en-todo-el-archipielago\/","title":{"rendered":"El Gobierno de Canarias declara la situaci\u00f3n de prealerta por fen\u00f3menos costeros en todo el archipi\u00e9lago"},"content":{"rendered":"<p><strong>El Gobierno de Canarias, a trav\u00e9s de la Direcci\u00f3n General de Emergencias, declara la situaci\u00f3n de prealerta por fen\u00f3menos costeros en todas las islas a partir de las 00:00 horas, de ma\u00f1ana martes, 26 de marzo.<\/strong><\/p>\n<p>Esta decisi\u00f3n se toma teniendo en cuenta la informaci\u00f3n facilitada por la Agencia Estatal de Meteorolog\u00eda y otras fuentes disponibles, y en aplicaci\u00f3n del Plan Espec\u00edfico de Emergencias de Canarias por Riesgos de Fen\u00f3menos Meteorol\u00f3gicos Adversos (PEFMA).<\/p>\n<p><strong>\u00c1mbito territorial:\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>Canarias<\/p>\n<p><strong>Observaciones:<\/strong><\/p>\n<p>La previsi\u00f3n meteorol\u00f3gica apunta a mal estado del mar, especialmente en las costas del norte de todas las islas, y en las del oeste de La Palma, El Hierro, Fuerteventura y Lanzarote. Se prev\u00e9 oleaje de mar combinada de 2,5 a cuatro metros. Adem\u00e1s, este martes, 26 de marzo habr\u00e1 viento del norte y noroeste fuerza seis a siete (de entre 39 y 61 kil\u00f3metros por hora) y ocasionalmente fuerza ocho (de entre 62 y 74 kil\u00f3metros por hora) en el mar entre la vertiente este y sureste de La Gomera y la vertiente oeste de Tenerife.<\/p>\n<p>Se insta a la poblaci\u00f3n a seguir los siguientes\u00a0<a href=\"https:\/\/www.gobiernodecanarias.org\/emergencias\/alertas\/consejos\/costeros\/costeros.html\" target=\"_blank\" rel=\"noopener\">consejos de autoprotecci\u00f3n\u00a0<\/a>de la Direcci\u00f3n General de Emergencias.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6203\" class=\"pvc_stats all  \" data-element-id=\"6203\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <\/p>\n<div class=\"pvc_clear\"><\/div>\n<div class=\"print\"><span class=\"page_title\">P\u00e1gina: <span>El Gobierno de Canarias declara la situaci\u00f3n de prealerta por fen\u00f3menos costeros en todo el archipi\u00e9lago<\/span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"stmp_trans_date\">\u00daltima actualizaci\u00f3n: <span>25\/03\/2024 - 15:20:13<\/span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"stmp_trans_date\">Fecha publicaci\u00f3n: <span>25\/03\/2024 - 15:20:13<\/span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"stmp_trans_date\">Fecha creaci\u00f3n: <span>25\/03\/2024 - 15:20:13<\/span><\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Canarias, a trav\u00e9s de la Direcci\u00f3n General de Emergencias, declara la situaci\u00f3n de prealerta por fen\u00f3menos costeros en todas las islas a partir de las 00:00 horas, de ma\u00f1ana martes, 26 de marzo. Esta decisi\u00f3n se toma teniendo en cuenta la informaci\u00f3n&#8230;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6203\" class=\"pvc_stats all  \" data-element-id=\"6203\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.112canarias.com\/112\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":5,"featured_media":6204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-6203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts\/6203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/comments?post=6203"}],"version-history":[{"count":1,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts\/6203\/revisions"}],"predecessor-version":[{"id":6205,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/posts\/6203\/revisions\/6205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/media\/6204"}],"wp:attachment":[{"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/media?parent=6203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/categories?post=6203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.112canarias.com\/112\/wp-json\/wp\/v2\/tags?post=6203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}